{"id":1910,"date":"2025-09-10T14:15:41","date_gmt":"2025-09-10T14:15:41","guid":{"rendered":"https:\/\/eltercerpoder.com\/?p=1910"},"modified":"2025-09-10T17:03:24","modified_gmt":"2025-09-10T17:03:24","slug":"la-presidenta-del-ts-y-del-cgpj-recuerda-que-los-poderes-del-estado-estan-exigidos-a-sostener-con-su-actuacion-cotidiana-la-confianza-en-la-justicia","status":"publish","type":"post","link":"https:\/\/eltercerpoder.com\/index.php\/2025\/09\/10\/la-presidenta-del-ts-y-del-cgpj-recuerda-que-los-poderes-del-estado-estan-exigidos-a-sostener-con-su-actuacion-cotidiana-la-confianza-en-la-justicia\/","title":{"rendered":"La presidenta del TS y del CGPJ recuerda que los poderes del Estado est\u00e1n exigidos \u201ca sostener con su actuaci\u00f3n cotidiana la confianza en la Justicia\u201d"},"content":{"rendered":"<p>En el acto de apertura del A\u00f1o Judicial, Isabel Perell\u00f3 dice que \u201cla sociedad no merece que los poderes p\u00fablicos entren en descalificaciones ni en reproches mutuos, sino que las instituciones funcionen con normalidad y que act\u00faen al servicio de los ciudadanos y con respeto y lealtad a las otras\u201d. Considera superado el primer desaf\u00edo que asumi\u00f3 el CGPJ, que en su primer a\u00f1o de mandato ha normalizado la situaci\u00f3n de la planta judicial con los 161 nombramientos realizados, todos ellos por unanimidad o amplio consenso<\/p>\n<p>La presidenta del Tribunal Supremo y del Consejo General del Poder Judicial, Isabel Perell\u00f3, ha afirmado hoy, durante su intervenci\u00f3n en el acto de apertura del A\u00f1o Judicial que Su Majestad el Rey ha presidido en el Tribunal Supremo, que sostener con su actuaci\u00f3n cotidiana la confianza y la credibilidad en la Justicia es una \u201cexigencia\u201d que obliga a todos los poderes del Estado, porque de ellas depende la fortaleza misma del Estado de Derecho, y ha calificado de \u201cinoportunas y rechazables\u201d las insistentes descalificaciones a la Justicia provenientes de los poderes p\u00fablicos.<\/p>\n<p>Tras recordar que el informe sobre el Estado de Derecho en Espa\u00f1a aprobado el pasado julio por la Comisi\u00f3n Europea advert\u00eda que \u201clos poderes Ejecutivo y Legislativo deben evitar caer en cr\u00edticas que minen la independencia judicial o la confianza p\u00fablica en esta\u201d, Perell\u00f3 ha dicho que \u201ctal forma de proceder, adem\u00e1s de contradecir la recomendaci\u00f3n europea, socava de forma directa la confianza en la Justicia, al tratar de influir negativamente en la consideraci\u00f3n ciudadana de los jueces\u201d.<\/p>\n<p>\u201cEstas descalificaciones son impropias de un Estado de Derecho avanzado en el que rige no solo el principio de separaci\u00f3n de poderes, sino tambi\u00e9n el de respeto mutuo; en definitiva, la lealtad institucional\u201d, ha a\u00f1adido la presidenta del TS y del CGPJ, que ha dicho que son aceptables y leg\u00edtimos el desacuerdo y la cr\u00edtica, \u201cpero no lo es desacreditar al Poder Judicial, atribuy\u00e9ndole intenciones u objetivos que resultan abiertamente contrarios a los principios que deben presidir la actuaci\u00f3n jurisdiccional\u201d.<\/p>\n<p>Tambi\u00e9n ha manifestado que es en el seno del proceso judicial, \u201cque se desarrolla con todas las garant\u00edas de audiencia y defensa\u201d, donde toda actuaci\u00f3n judicial \u201ces susceptible de ser revisada por otros jueces imparciales e independientes\u201d; y ha recordado que \u201cel Estado de Derecho protege los derechos de cualquier persona sometida a un procedimiento judicial bajo la premisa de la presunci\u00f3n de inocencia y de la igualdad de todos los ciudadanos ante la ley\u201d.<\/p>\n<p>\u201cNo es propio del Poder Judicial entrar en pol\u00e9micas ni en cr\u00edticas a personas ni a instituciones, pues no nos corresponde esa funci\u00f3n. Cada cargo p\u00fablico es responsable de sus actos. Pero s\u00ed vamos a defender con firmeza los principios esenciales que definen al Poder Judicial y que hacen que sea digno de este nombre\u201d, ha a\u00f1adido Perell\u00f3, que ha se\u00f1alado que \u201cla sociedad no merece que los poderes p\u00fablicos entren en descalificaciones ni en reproches mutuos, sino que las instituciones funcionen con normalidad y que act\u00faen al servicio de los ciudadanos, y con respeto y lealtad a las otras. Y as\u00ed lo har\u00e1 el Poder Judicial\u201d.<\/p>\n<p><strong>Independencia judicial<\/strong><\/p>\n<p>La presidenta del TS y del CGPJ ha asegurado asimismo que los jueces no obedecen \u00f3rdenes ni instrucciones de nadie en el ejercicio de su funci\u00f3n, pero que \u201cindependencia no equivale a libre arbitrio\u201d ni es, \u201cen modo alguno, un privilegio de los jueces, sino una garant\u00eda de los ciudadanos y nuestro primer deber. Cada uno de nosotros estamos llamados a preservarla, porque constituye la condici\u00f3n imprescindible para que el poder judicial cumpla con su funci\u00f3n constitucional: la tutela judicial efectiva de los derechos e intereses de todos\u201d.<\/p>\n<p>Adem\u00e1s, ha recordado que el \u00e1mbito de la independencia judicial es absoluto y que todos est\u00e1n obligados a respetarla, tal y como dispone la Ley Org\u00e1nica del Poder Judicial, y ha subrayado que \u201cese respeto no es una f\u00f3rmula ret\u00f3rica: exige que no se nos presione, que no se nos condicione, que no se erosione la credibilidad de los tribunales con juicios de oportunidad pol\u00edtica o de cualquier tipo ni con expectativas que desconocen los principios y los tiempos del proceso\u201d.<\/p>\n<p>Por \u00faltimo, la presidenta del TS y del CGPJ ha asegurado que, a pesar de las descalificaciones, \u201cel Poder Judicial no va a desviarse de su camino de rectitud y honestidad. Nuestra funci\u00f3n es resolver los conflictos que se dan en la sociedad, no contribuir a alimentarlos. Los hombres y mujeres que servimos a la Justicia seguiremos desempe\u00f1ando nuestra labor con independencia, rigor y vocaci\u00f3n de servicio, lo que constituye la mejor garant\u00eda de los derechos de todos, lejos de disputas est\u00e9riles que nada aportan\u201d.<\/p>\n<p><strong>Normalizaci\u00f3n de la planta judicial<\/strong><\/p>\n<p>Durante su intervenci\u00f3n en el acto de apertura del A\u00f1o Judicial, la presidenta del CGPJ ha hecho balance del primer a\u00f1o de mandato de la instituci\u00f3n y ha dado por superado el primer desaf\u00edo al que se enfrent\u00f3 \u00e9sta: cubrir las numerosas vacantes en plazas judiciales, 31 de ellas en el Tribunal Supremo.<\/p>\n<p>Desde entonces, el \u00f3rgano de gobierno de los jueces ha conseguido normalizar la planta judicial al hacer 161 nombramientos, la inmensa mayor\u00eda de ellos por unanimidad o amplio consenso.<\/p>\n<p>\u201cEl Consejo ha cumplido con su cometido con rigor y responsabilidad en este primer a\u00f1o, velando por el inter\u00e9s superior del servicio p\u00fablico de la Justicia\u201d, ha concluido Perell\u00f3, que ha confiado en que la instituci\u00f3n afrontar\u00e1 con la misma responsabilidad otros desaf\u00edos de gran envergadura como la implantaci\u00f3n de los tribunales de instancia o dar una respuesta eficaz a la litigaci\u00f3n en masa.<\/p>\n<p>En este sentido, ha asegurado que desde la presidencia del \u00f3rgano constitucional se esforzar\u00e1 siempre \u201cpor alcanzar el consenso y conseguir decisiones aceptadas por amplias mayor\u00edas, pues est\u00e1 llamada a ejercer un papel imparcial y neutral, garante del correcto funcionamiento del Poder judicial, al servicio exclusivo de la justicia y del inter\u00e9s general\u201d.<\/p>\n<p>\u201cComo presidenta -ha a\u00f1adido- mi compromiso es ejercer mi funci\u00f3n con independencia, firmeza, con criterio propio y con la m\u00e1xima lealtad institucional\u201d.<strong>\u00a0<\/strong><\/p>\n<p><strong>Compromiso con la igualdad<\/strong><\/p>\n<p>La presidenta del TS y del CGPJ ha se\u00f1alado tambi\u00e9n que el Consejo debe seguir avanzando en su compromiso con la igualdad entre hombres y mujeres, recordando que de los 161 nombramientos realizados este a\u00f1o el 42 % han reca\u00eddo en candidatas mujeres, porcentaje que se eleva al 53 % si se tienen en cuenta solamente aquellas plazas a las que concurr\u00edan candidatos de ambos sexos.<\/p>\n<p>\u201cSin duda, queda mucho camino por recorrer, pero ya estamos asistiendo a un verdadero cambio en la c\u00fapula del poder judicial y conf\u00edo en que a lo largo de este mandato se consiga la igualdad en el \u00e1mbito judicial. Ese es mi empe\u00f1o\u201d, ha dicho Perell\u00f3, que ha reiterado su reconocimiento a las mujeres que han luchado por la defensa del derecho a la igualdad \u201cy por acabar con la injusta falta de consideraci\u00f3n a la que nos hemos visto sometidas en distintos \u00e1mbitos de la vida profesional y social\u201d.<\/p>\n<p><strong>Alarmante falta de jueces<\/strong><\/p>\n<p>Perell\u00f3 ha asegurado que, al igual que el CGPJ ha cumplido \u201ccon rigor y responsabilidad\u201d su funci\u00f3n constitucional, \u201ctambi\u00e9n puede afirmarse que lo ha hecho el Poder Judicial como poder del Estado\u201d, y ha recordado que en 2024 los Juzgados y Tribunales resolvieron 7 millones de asuntos y dictaron m\u00e1s de dos millones de sentencias -800.000 y 300.000 m\u00e1s que el a\u00f1o anterior, respectivamente-, lo que significa que, de media, cada juez resolvi\u00f3 cerca de 1.400 asuntos y dict\u00f3 325 sentencias.<\/p>\n<p>\u201cEstas cifras reflejan la responsabilidad y el sobresfuerzo de los miembros del Poder Judicial\u201d, ha dicho la presidenta del \u00f3rgano de gobierno de los jueces, que ha se\u00f1alado que la media de jueces por cada cien mil habitantes en Espa\u00f1a es muy inferior a la de los pa\u00edses del Consejo de Europa (11,9 frente a 17,4) y que la falta de jueces \u201cresulta alarmante\u201d, ya que las 120 plazas que, de media, se han ofrecido en las convocatorias de los \u00faltimos a\u00f1os son insuficientes para alcanzar la tasa de reposici\u00f3n y que el CGPJ considera urgente la creaci\u00f3n de 509 plazas judiciales.<\/p>\n<p>\u201cEsta es una de nuestras grandes preocupaciones, cuya soluci\u00f3n no puede demorarse ni quedar supeditada al incierto devenir de determinadas iniciativas legislativas\u201d, ha se\u00f1alado Perell\u00f3, que ha agregado que la falta de jueces \u201cpone en grave riesgo la efectividad de la Justicia, garant\u00eda \u00faltima de los derechos de los ciudadanos\u201d.<\/p>\n<p>La presidenta del TS y del CGPJ ha advertido, no obstante, de que el necesario incremento del n\u00famero de jueces \u201cno puede hacerse en detrimento de la calidad de la formaci\u00f3n que exige la funci\u00f3n jurisdiccional\u201d y que las reformas en el sistema de selecci\u00f3n que puedan plantearse en el futuro deben respetar siempre sus principios esenciales: la publicidad, la objetividad de las pruebas, que se basa en control del conocimiento exhaustivo del Derecho, y la transparencia.<\/p>\n<p><strong>Medidas contra las dilaciones en los procedimientos judiciales<\/strong><\/p>\n<p>Otro de los problemas que suscitan preocupaci\u00f3n en el \u00f3rgano de gobierno de los jueces, ha subrayado su presidenta, es el de las dilaciones que sufren los procedimientos judiciales, que son \u201cinaceptables en una sociedad democr\u00e1tica avanzada\u201d.<\/p>\n<p>\u201cUna justicia tard\u00eda no es una justicia efectiva. Es urgente poner en marcha medidas que terminen con este problema, que contribuye a minar la confianza en la Justicia\u201d, ha manifestado antes de reclamar la regulaci\u00f3n del Gabinete T\u00e9cnico del Tribunal Supremo prevista en la Ley 7\/2015, pendiente desde hace m\u00e1s de diez a\u00f1os y que ha considerado \u201cvital\u201d para el funcionamiento del alto tribunal.<\/p>\n<p><strong>Reformas legislativas: di\u00e1logo institucional y participaci\u00f3n del CGPJ<\/strong><\/p>\n<p>Perell\u00f3 ha asegurado tambi\u00e9n que los jueces no son inmovilistas, sino que constantemente reclaman mejoras y reformas, pero que estas \u201cdeben tener como finalidad profundizar en nuestra formaci\u00f3n e independencia y no pueden darse pasos que signifiquen un retroceso en estos elementos esenciales\u201d.<\/p>\n<p>\u201cExisten reformas en tramitaci\u00f3n que afectan directamente a la Carrera Judicial y que generan leg\u00edtima preocupaci\u00f3n en la judicatura\u201d, ha dicho la presidenta del CGPJ, que ha se\u00f1alado que \u201ces, obviamente, al legislador al que corresponde aprobar estas reformas, pero deben elaborarse mediante el di\u00e1logo institucional y con la participaci\u00f3n del Consejo General del Poder Judicial, que ha de aportar la experiencia y el conocimiento necesarios para mejorar el ejercicio de la funci\u00f3n jurisdiccional\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el acto de apertura del A\u00f1o Judicial, Isabel Perell\u00f3 dice que \u201cla sociedad no merece que los poderes p\u00fablicos entren en descalificaciones ni en reproches mutuos, sino que las instituciones funcionen con normalidad y que act\u00faen al servicio de los ciudadanos y con respeto y lealtad a las otras\u201d. Considera superado el primer desaf\u00edo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"amp_status":"","footnotes":""},"categories":[100,6],"tags":[],"class_list":["post-1910","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-justicia","category-style","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/posts\/1910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/comments?post=1910"}],"version-history":[{"count":2,"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/posts\/1910\/revisions"}],"predecessor-version":[{"id":1914,"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/posts\/1910\/revisions\/1914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/media\/1913"}],"wp:attachment":[{"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/media?parent=1910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/categories?post=1910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltercerpoder.com\/index.php\/wp-json\/wp\/v2\/tags?post=1910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}